{"id":78,"count":1,"description":"","link":"https:\/\/kosugi-clinic.net\/blog\/tag\/%e5%b0%8f%e6%9e%97%e9%ba%bb%e5%a4%ae%e3%80%80%e6%80%9d%e3%81%86%e3%81%93%e3%81%a8\/","name":"\u5c0f\u6797\u9ebb\u592e\u3000\u601d\u3046\u3053\u3068","slug":"%e5%b0%8f%e6%9e%97%e9%ba%bb%e5%a4%ae%e3%80%80%e6%80%9d%e3%81%86%e3%81%93%e3%81%a8","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/kosugi-clinic.net\/blog\/wp-json\/wp\/v2\/tags\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kosugi-clinic.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kosugi-clinic.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kosugi-clinic.net\/blog\/wp-json\/wp\/v2\/posts?tags=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}